{"id":299,"date":"2021-04-18T08:29:15","date_gmt":"2021-04-18T07:29:15","guid":{"rendered":"https:\/\/www.duplicata-permis-de-conduire.fr\/blog\/?p=299"},"modified":"2021-05-03T15:43:07","modified_gmt":"2021-05-03T14:43:07","slug":"photo-signature-permis-conduire","status":"publish","type":"post","link":"https:\/\/www.duplicata-permis-de-conduire.fr\/blog\/photo-signature-permis-conduire\/","title":{"rendered":"Demande de permis de conduire en ligne : la photo-signature num\u00e9rique"},"content":{"rendered":"<h1 style=\"text-align: center;\">Demande de permis de conduire en ligne : la photo-signature num\u00e9rique<\/h1>\n<p><span style=\"font-weight: 400;\">Pour une <a href=\"https:\/\/www.duplicata-permis-de-conduire.fr\/\">demande de permis de conduire<\/a>, il n\u2019est plus obligatoire de se d\u00e9placer et de se rendre \u00e0 la Pr\u00e9fecture.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il suffit d\u2019avoir une tablette, un Smartphone ou un ordinateur et le tour est jou\u00e9.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La\u00a0 r\u00e9alisation des d\u00e9marches en ligne pour une demande de permis est possible pour plusieurs cas\u00a0:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">demande d\u2019inscription au permis de conduire pour passer des examens<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">demande de titre apr\u00e8s la r\u00e9ussite \u00e0 l\u2019examen permis conduire ou en cas de vol, de perte ou de d\u00e9t\u00e9rioration de permis<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">demande de renouvellement de titre de permis<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">En effet, les \u00e9l\u00e9ments de la demande sont r\u00e9cemment transmis de fa\u00e7on d\u00e9mat\u00e9rialis\u00e9e. Ce sont les donn\u00e9es d\u2019\u00e9tat civil, les pi\u00e8ces justificatives, la photo et la signature. Pour comprendre o\u00f9 faire la photo-signature num\u00e9rique, consid\u00e9rez ce guide.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Les \u00e9tapes pr\u00e9alables \u00e0 la demande de permis de conduire en ligne<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">D\u2019abord, lors d\u2019une <\/span><b>demande de permis de conduire en ligne<\/b><span style=\"font-weight: 400;\">, il faut cr\u00e9er un compte personnel usager sur <\/span><span style=\"font-weight: 400;\">le<a href=\"https:\/\/www.duplicata-permis-de-conduire.fr\/blog\/site-ants-tuto-comprendre\/\"> site de l\u2019ANTS<\/a><\/span><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De l\u00e0, vous recevez vos identifiants.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ensuite, il faut se connecter une fois sur la rubrique Mon Espace et cr\u00e9er un compte en pr\u00e9cisant les informations exig\u00e9es.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Apr\u00e8s cela, vous recevez un courriel qui vous demande l\u2019activation de votre compte, puis un formulaire \u00e0 remplir pour le choix de votre mot de passe.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vous commencez les d\u00e9marches en ligne apr\u00e8s avoir compl\u00e9t\u00e9 le formulaire. En m\u00eame temps, vous recevez un courriel qui indique votre identifiant.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dans le cas d\u2019une demande par une personne mineure, un repr\u00e9sentant l\u00e9gal est exig\u00e9.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Les principales \u00e9tapes de la proc\u00e9dure d\u00e9mat\u00e9rialis\u00e9e<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Des \u00e9tapes sont \u00e0 suivre pour faire une demande de permis de conduire en ligne. Cela peut s\u2019agir d\u2019une demande de titre apr\u00e8s r\u00e9ussite \u00e0 l\u2019examen ou d\u2019une <\/span><span style=\"font-weight: 400;\">demande de renouvellement de <a href=\"https:\/\/www.duplicata-permis-de-conduire.fr\/blog\/renouveler-permis-conduire-duplicata\/\">permis de conduire, de duplicata ou de cat\u00e9gorie AM apr\u00e8s annulation, suspension ou invalidation<\/a><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Premi\u00e8rement, il est n\u00e9cessaire de renseigner les informations et les pi\u00e8ces justificatives indispensables \u00e0 la d\u00e9marche. Ces derni\u00e8res doivent \u00eatre de <\/span><b>format num\u00e9rique<\/b><span style=\"font-weight: 400;\">, scann\u00e9 ou photographi\u00e9.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Ce sont\u00a0:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">l\u2019adresse mail<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">le num\u00e9ro de t\u00e9l\u00e9phone portable<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">la carte nationale d\u2019identit\u00e9 et la photo d\u2019identit\u00e9 num\u00e9rique<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">le passeport<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">le justificatif de r\u00e9gularit\u00e9 de s\u00e9jour<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">l\u2019avis m\u00e9dical d\u2019un m\u00e9decin en cas de <\/span><b>renouvellement<\/b><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">En cas de demande d\u2019extension de cat\u00e9gorie, il faut une copie du permis de conduire.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Deuxi\u00e8mement, il faut remplir <\/span><b>le formulaire<\/b><span style=\"font-weight: 400;\"> correctement, quel que soit le motif de la demande de permis.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Apr\u00e8s le d\u00e9p\u00f4t de la demande, vous recevez une attestation d\u2019inscription au permis.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">S\u2019acquitter du droit du timbre est l\u2019\u00e9tape suivante. Ce dernier co\u00fbte environ 25 euros. C\u2019est valable pour le renouvellement de permis ou en cas de perte voire de vol de votre permis de conduire.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Le paiement de cette taxe est bien \u00e9videmment <\/span><b>d\u00e9mat\u00e9rialis\u00e9<\/b><span style=\"font-weight: 400;\"> aussi. La preuve du paiement est t\u00e9l\u00e9chargeable comme justificatif compl\u00e9mentaire. Elle permet ensuite de valider votre demande de permis de conduire.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Quatri\u00e8mement, c\u2019est le suivi de l\u2019avancement de votre dossier de\u00a0 demande. Pour une demande de titres, cela est possible gr\u00e2ce \u00e0 votre compte usager.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Derni\u00e8rement, c\u2019est la r\u00e9ception du permis de conduire.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Pour un renouvellement suite \u00e0 un vol, le permis vous sera livr\u00e9 directement dans votre domicile. En cas d\u2019absence, vous avez deux semaines pour le r\u00e9cup\u00e9rer \u00e0 la poste. Sinon, vous\u00a0 devez vous rendre \u00e0 la pr\u00e9fecture.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Proc\u00e9der \u00e0 l\u2019e-photo pour son permis de conduire<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Il est primordial de fournir une <\/span><b>photo num\u00e9rique<\/b><span style=\"font-weight: 400;\"> lors d\u2019une demande en ligne de permis de conduire.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pour se procurer une ephoto pour votre permis, une d\u00e9marche simple est \u00e0 respecter.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En effet, la photo num\u00e9rique d\u2019identit\u00e9 ou la photo signature num\u00e9rique est r\u00e9alisable \u00e0 distance. Apr\u00e8s la r\u00e9alisation de la photo, vous recevez un <\/span><b>num\u00e9ro ephoto<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Apr\u00e8s cela, vous devez saisir le<\/span><b> code <\/b><span style=\"font-weight: 400;\">du num\u00e9ro de votre photo num\u00e9ris\u00e9e dans la d\u00e9marche de demande en ligne. De l\u00e0, vous pouvez facilement ajouter votre photo num\u00e9rique pour valider votre demande.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Concernant la signature num\u00e9rique<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">La <\/span><b>signature num\u00e9rique<\/b><span style=\"font-weight: 400;\"> est aussi exig\u00e9e lorsque vous effectuez une demande de permis en ligne. Il s\u2019agit en fait d\u2019un moyen efficace pour assurer l\u2019int\u00e9grit\u00e9 de votre document \u00e9lectronique. La signature permet aussi de v\u00e9rifier votre identit\u00e9.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">NB\u00a0: Une signature num\u00e9rique est diff\u00e9rente d\u2019une signature \u00e9lectronique. Elle n\u2019est pas du tout visuelle.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La signature d\u00e9mat\u00e9rialis\u00e9e pour permis de conduire permet essentiellement de faire une demande de permis de conduire ou de renouvellement de celui-ci sur internet. En parall\u00e8le avec la prise de la photo, il faut apposer sa signature.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pour ce faire, vous devez utiliser un stylet sur votre \u00e9cran tactile ou sur votre tablette.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Comme pour l\u2019ephoto, vos donn\u00e9es seront envoy\u00e9es \u00e0 l\u2019administration et cette derni\u00e8re vous fournira un code compos\u00e9 de 22 chiffres avec votre signature. Il ne vous reste plus qu\u2019\u00e0 renseigner ce code envoy\u00e9 sur le site de l\u2019ANTS.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">O\u00f9 faire la photo-signature num\u00e9ris\u00e9e alors\u00a0?<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Pour faire de la photo et de la signature num\u00e9ris\u00e9e, plusieurs solutions s\u2019ouvrent\u00a0 \u00e0 vous. En effet, des adresses vari\u00e9es permettent la r\u00e9alisation de vos photos num\u00e9riques d\u2019identit\u00e9 ainsi que votre signature pour permis en ligne.<\/span><\/p>\n<h3><b>chez un photographe professionnel<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">La photo et la signature pour une demande de permis en ligne sont r\u00e9alisables chez un photographe professionnel.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vous trouverez la liste des photographes agr\u00e9\u00e9s sur le site de l\u2019ANTS. Ces derniers sont rep\u00e9rables par la pr\u00e9sence de vignette bleue. Un sigle qui justifie l&#8217;habilet\u00e9 du professionnel \u00e0 faire de la photo-signature num\u00e9ris\u00e9e.<\/span><\/p>\n<h3><b>dans un photomaton<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Faites votre photo et signature num\u00e9rique dans un <\/span><b>photomaton<\/b><span style=\"font-weight: 400;\">. Cela se fait dans une cabine. C\u2019est-\u00e0-dire, aupr\u00e8s des cabines automatiques agr\u00e9\u00e9es ANTS. Comme pour les photographes, vous les reconna\u00eetrez par la pr\u00e9sence d\u2019une vignette bleue.<\/span><\/p>\n<h3><b>\u00e0 la maison<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Vous pouvez faire vos photos pour le permis de conduire chez vous. C\u2019est possible si vous avez un Smartphone iD qui utilise l\u2019agr\u00e9ment de l\u2019ANTS. Ceci est disponible sur iPhone et Android.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il permet\u00a0 de choisir une photo et de signer votre planche ephoto. Vous recevez vos photos par courrier postal ou par mail par la suite.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Demande de permis de conduire en ligne : la photo-signature num\u00e9rique Pour une demande de permis de conduire, il n\u2019est plus obligatoire de se d\u00e9placer et de se rendre \u00e0 la Pr\u00e9fecture. Il suffit d\u2019avoir une tablette, un Smartphone ou un ordinateur et le tour est jou\u00e9. La\u00a0 r\u00e9alisation des d\u00e9marches en ligne pour une [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":302,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.duplicata-permis-de-conduire.fr\/blog\/wp-json\/wp\/v2\/posts\/299"}],"collection":[{"href":"https:\/\/www.duplicata-permis-de-conduire.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.duplicata-permis-de-conduire.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.duplicata-permis-de-conduire.fr\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.duplicata-permis-de-conduire.fr\/blog\/wp-json\/wp\/v2\/comments?post=299"}],"version-history":[{"count":5,"href":"https:\/\/www.duplicata-permis-de-conduire.fr\/blog\/wp-json\/wp\/v2\/posts\/299\/revisions"}],"predecessor-version":[{"id":459,"href":"https:\/\/www.duplicata-permis-de-conduire.fr\/blog\/wp-json\/wp\/v2\/posts\/299\/revisions\/459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.duplicata-permis-de-conduire.fr\/blog\/wp-json\/wp\/v2\/media\/302"}],"wp:attachment":[{"href":"https:\/\/www.duplicata-permis-de-conduire.fr\/blog\/wp-json\/wp\/v2\/media?parent=299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.duplicata-permis-de-conduire.fr\/blog\/wp-json\/wp\/v2\/categories?post=299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.duplicata-permis-de-conduire.fr\/blog\/wp-json\/wp\/v2\/tags?post=299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}